{"id":31367,"date":"2026-05-19T07:52:37","date_gmt":"2026-05-19T07:52:37","guid":{"rendered":"https:\/\/nichitastore.ro\/produs\/papusa-bebelus-salopeta-unicorn-28-cm\/"},"modified":"2026-06-29T14:27:28","modified_gmt":"2026-06-29T14:27:28","slug":"papusa-bebelus-salopeta-unicorn-28-cm","status":"publish","type":"product","link":"https:\/\/nichitastore.ro\/ro\/produs\/papusa-bebelus-salopeta-unicorn-28-cm\/","title":{"rendered":"Papusa Bebelus salopeta Unicorn, 28 cm"},"content":{"rendered":"<p>Papusa Bebelus Dragalas cu salopeta \u2013 28 cm <br \/> Adauga un zambet pe chipul copilului tau cu aceasta adorabila papusa bebelus! Realizata cu grija si atentie la detalii, aceasta papusica este ideala pentru joaca, imbratisari sau cadouri speciale.<\/p>\n<p>Materiale:<\/p>\n<p>Papusa fabricata complet din plastic rezistent, placut la atingere<\/p>\n<p> Imbracaminte: <br \/> Salopeta vesela cu unicorn si curcubeu<br \/> Caciulita roz moale, usor de scos si pus<br \/>Instructiuni de intretinere &#038; avertismente materiale:<\/p>\n<p>Hainele si caciulita pot fi spalate manual la max. 30\u00b0C, cu detergent delicat<\/p>\n<p>Papusa se curata cu o laveta moale, usor umeda<\/p>\n<p>A nu se scufunda complet in apa! \u2013 Nu este o jucarie de baie<\/p>\n<p>Nu se recomanda spalarea la masina, uscarea automata sau calcarea<\/p>\n<p> Jucarie nerecomandata copiilor sub 3 ani fara supravegherea unui adult \u2013 contine parti detasabile.<\/p>\n<p>Made in China<\/p>\n<p>Avertisment! <\/p>\n<p>Asigurati-va ca jucaria aleasa este potrivita pentru varsta copilului. <\/p>\n<p>Pentru a evita orice accident nu atasati cordoane, sfori sau alte obiecte de jucarie.<br \/> Fotografia prezentata are caracter informativ si pot exista diferente intre aceasta si produs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Papusa Bebelus Dragalas cu salopeta \u2013 28 cm Adauga un zambet pe chipul copilului tau cu aceasta adorabila papusa bebelus!<\/p>\n","protected":false},"featured_media":31366,"template":"","meta":{"_acf_changed":false},"product_brand":[76],"product_cat":[119,121],"product_tag":[],"class_list":{"0":"post-31367","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-nichita","7":"product_cat-jucarii-si-jocuri","8":"product_cat-papusi","9":"pa_culoare-multicolor","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/nichitastore.ro\/ro\/wp-json\/wp\/v2\/product\/31367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nichitastore.ro\/ro\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nichitastore.ro\/ro\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/nichitastore.ro\/ro\/wp-json\/wp\/v2\/product\/31367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nichitastore.ro\/ro\/wp-json\/wp\/v2\/media\/31366"}],"wp:attachment":[{"href":"https:\/\/nichitastore.ro\/ro\/wp-json\/wp\/v2\/media?parent=31367"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nichitastore.ro\/ro\/wp-json\/wp\/v2\/product_brand?post=31367"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nichitastore.ro\/ro\/wp-json\/wp\/v2\/product_cat?post=31367"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nichitastore.ro\/ro\/wp-json\/wp\/v2\/product_tag?post=31367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}